{"id":1152,"date":"2025-10-17T09:45:11","date_gmt":"2025-10-17T07:45:11","guid":{"rendered":"https:\/\/brandschutz-service.berlin\/?page_id=1152"},"modified":"2026-01-07T13:34:30","modified_gmt":"2026-01-07T12:34:30","slug":"brandschutzglas-fuer-sicherheit-im-brandschutz","status":"publish","type":"page","link":"https:\/\/brandschutz-service.berlin\/de\/brandschutz-ratgeber\/materialien-bauteile\/brandschutzglas-fuer-sicherheit-im-brandschutz\/","title":{"rendered":"Brandschutzglas f\u00fcr Sicherheit im Brandschutz"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":1089,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/page-ratgeber.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1152","page","type-page","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brandschutzglas: Sicherheit &amp; Schutzklassen im \u00dcberblick<\/title>\n<meta name=\"description\" content=\"Brandschutzglas erm\u00f6glicht helle, sichere R\u00e4ume. Erfahren Sie alles \u00fcber Brandschutzklassen, Feuerwiderstandsdauer und die Wahl des richtigen Glases.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brandschutz-service.berlin\/de\/brandschutz-ratgeber\/materialien-bauteile\/brandschutzglas-fuer-sicherheit-im-brandschutz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brandschutzglas: Sicherheit &amp; Schutzklassen im \u00dcberblick\" \/>\n<meta property=\"og:description\" content=\"Brandschutzglas erm\u00f6glicht helle, sichere R\u00e4ume. Erfahren Sie alles \u00fcber Brandschutzklassen, Feuerwiderstandsdauer und die Wahl des richtigen Glases.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brandschutz-service.berlin\/de\/brandschutz-ratgeber\/materialien-bauteile\/brandschutzglas-fuer-sicherheit-im-brandschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"Brandschutz Service Berlin\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-07T12:34:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/brandschutz-service.berlin\\\/de\\\/brandschutz-ratgeber\\\/materialien-bauteile\\\/brandschutzglas-fuer-sicherheit-im-brandschutz\\\/\",\"url\":\"https:\\\/\\\/brandschutz-service.berlin\\\/de\\\/brandschutz-ratgeber\\\/materialien-bauteile\\\/brandschutzglas-fuer-sicherheit-im-brandschutz\\\/\",\"name\":\"Brandschutzglas: Sicherheit & Schutzklassen im \u00dcberblick\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brandschutz-service.berlin\\\/de\\\/#website\"},\"datePublished\":\"2025-10-17T07:45:11+00:00\",\"dateModified\":\"2026-01-07T12:34:30+00:00\",\"description\":\"Brandschutzglas erm\u00f6glicht helle, sichere R\u00e4ume. Erfahren Sie alles \u00fcber Brandschutzklassen, Feuerwiderstandsdauer und die Wahl des richtigen Glases.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/brandschutz-service.berlin\\\/de\\\/brandschutz-ratgeber\\\/materialien-bauteile\\\/brandschutzglas-fuer-sicherheit-im-brandschutz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/brandschutz-service.berlin\\\/de\\\/brandschutz-ratgeber\\\/materialien-bauteile\\\/brandschutzglas-fuer-sicherheit-im-brandschutz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/brandschutz-service.berlin\\\/de\\\/brandschutz-ratgeber\\\/materialien-bauteile\\\/brandschutzglas-fuer-sicherheit-im-brandschutz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/brandschutz-service.berlin\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brandschutz-Ratgeber\",\"item\":\"https:\\\/\\\/brandschutz-service.berlin\\\/de\\\/brandschutz-ratgeber\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Materialien &amp; Bauteile\",\"item\":\"https:\\\/\\\/brandschutz-service.berlin\\\/de\\\/brandschutz-ratgeber\\\/materialien-bauteile\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Brandschutzglas f\u00fcr Sicherheit im Brandschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/brandschutz-service.berlin\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/brandschutz-service.berlin\\\/de\\\/\",\"name\":\"Brandschutz Service Berlin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/brandschutz-service.berlin\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brandschutzglas: Sicherheit & Schutzklassen im \u00dcberblick","description":"Brandschutzglas erm\u00f6glicht helle, sichere R\u00e4ume. Erfahren Sie alles \u00fcber Brandschutzklassen, Feuerwiderstandsdauer und die Wahl des richtigen Glases.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brandschutz-service.berlin\/de\/brandschutz-ratgeber\/materialien-bauteile\/brandschutzglas-fuer-sicherheit-im-brandschutz\/","og_locale":"de_DE","og_type":"article","og_title":"Brandschutzglas: Sicherheit & Schutzklassen im \u00dcberblick","og_description":"Brandschutzglas erm\u00f6glicht helle, sichere R\u00e4ume. Erfahren Sie alles \u00fcber Brandschutzklassen, Feuerwiderstandsdauer und die Wahl des richtigen Glases.","og_url":"https:\/\/brandschutz-service.berlin\/de\/brandschutz-ratgeber\/materialien-bauteile\/brandschutzglas-fuer-sicherheit-im-brandschutz\/","og_site_name":"Brandschutz Service Berlin","article_modified_time":"2026-01-07T12:34:30+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/brandschutz-service.berlin\/de\/brandschutz-ratgeber\/materialien-bauteile\/brandschutzglas-fuer-sicherheit-im-brandschutz\/","url":"https:\/\/brandschutz-service.berlin\/de\/brandschutz-ratgeber\/materialien-bauteile\/brandschutzglas-fuer-sicherheit-im-brandschutz\/","name":"Brandschutzglas: Sicherheit & Schutzklassen im \u00dcberblick","isPartOf":{"@id":"https:\/\/brandschutz-service.berlin\/de\/#website"},"datePublished":"2025-10-17T07:45:11+00:00","dateModified":"2026-01-07T12:34:30+00:00","description":"Brandschutzglas erm\u00f6glicht helle, sichere R\u00e4ume. Erfahren Sie alles \u00fcber Brandschutzklassen, Feuerwiderstandsdauer und die Wahl des richtigen Glases.","breadcrumb":{"@id":"https:\/\/brandschutz-service.berlin\/de\/brandschutz-ratgeber\/materialien-bauteile\/brandschutzglas-fuer-sicherheit-im-brandschutz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brandschutz-service.berlin\/de\/brandschutz-ratgeber\/materialien-bauteile\/brandschutzglas-fuer-sicherheit-im-brandschutz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/brandschutz-service.berlin\/de\/brandschutz-ratgeber\/materialien-bauteile\/brandschutzglas-fuer-sicherheit-im-brandschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/brandschutz-service.berlin\/de\/"},{"@type":"ListItem","position":2,"name":"Brandschutz-Ratgeber","item":"https:\/\/brandschutz-service.berlin\/de\/brandschutz-ratgeber\/"},{"@type":"ListItem","position":3,"name":"Materialien &amp; Bauteile","item":"https:\/\/brandschutz-service.berlin\/de\/brandschutz-ratgeber\/materialien-bauteile\/"},{"@type":"ListItem","position":4,"name":"Brandschutzglas f\u00fcr Sicherheit im Brandschutz"}]},{"@type":"WebSite","@id":"https:\/\/brandschutz-service.berlin\/de\/#website","url":"https:\/\/brandschutz-service.berlin\/de\/","name":"Brandschutz Service Berlin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brandschutz-service.berlin\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/brandschutz-service.berlin\/de\/wp-json\/wp\/v2\/pages\/1152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brandschutz-service.berlin\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/brandschutz-service.berlin\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/brandschutz-service.berlin\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brandschutz-service.berlin\/de\/wp-json\/wp\/v2\/comments?post=1152"}],"version-history":[{"count":0,"href":"https:\/\/brandschutz-service.berlin\/de\/wp-json\/wp\/v2\/pages\/1152\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/brandschutz-service.berlin\/de\/wp-json\/wp\/v2\/pages\/1089"}],"wp:attachment":[{"href":"https:\/\/brandschutz-service.berlin\/de\/wp-json\/wp\/v2\/media?parent=1152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}